{"id":65252,"date":"2019-09-13T14:12:43","date_gmt":"2019-09-13T12:12:43","guid":{"rendered":"https:\/\/tilefly.com\/producto\/imitacion-madera-porcelanico-baldosas-revestimiento-banos-salon-cocina-cara032723\/"},"modified":"2024-05-06T03:03:07","modified_gmt":"2024-05-06T01:03:07","slug":"imitacion-madera-porcelanico-baldosas-revestimiento-banos-salon-cocina-cara032723","status":"publish","type":"product","link":"https:\/\/tilefly.com\/nl\/product\/imitacion-madera-porcelanico-baldosas-revestimiento-banos-salon-cocina-cara032723\/","title":{"rendered":"TRAPECIO PALERMO MOKA 9,8X23"},"content":{"rendered":"<p>En TileFly encontrar\u00e1s la variedad m\u00e1s amplia de azulejos y revestimientos online. Nuestro equipo trabaja d\u00eda a d\u00eda para ofrecerte siempre las \u00faltimas tendencias en azulejos, mosaicos, baldosas y revestimientos. Trabajamos \u00fanicamente con fabricantes espa\u00f1oles e italianos de referencia. Estas empresas nos garantizan una excelente calidad y disponibilidad de los productos. Recordamos que todos los azulejos, revestimientos y piezas especiales que puedas encontrar en nuestra web tienen informaci\u00f3n espec\u00edfica de cada producto en el apartado &#8220;Informaci\u00f3n t\u00e9cnica&#8221;. Una vez realices tu pedido, nuestro equipo verificar\u00e1 que todas las caracter\u00edsticas del producto seleccionado sean correctas. Podr\u00eda ocurrir que alguno de estos datos sea err\u00f3neo o contenga alguna variaci\u00f3n. Nuestro equipo se encargar\u00e1 de comunicarte cualquier variaci\u00f3n para siempre tener tu conformidad para que te quedes seguro y, sobre todo, satisfecho del producto que has comprado.<\/p>","protected":false},"excerpt":{"rendered":"<p>En TileFly encontrar\u00e1s la variedad m\u00e1s amplia de azulejos y revestimientos online. Nuestro equipo trabaja d\u00eda a d\u00eda para ofrecerte siempre las \u00faltimas tendencias en azulejos, mosaicos, baldosas y revestimientos. Trabajamos \u00fanicamente con fabricantes espa\u00f1oles e italianos de referencia. Estas empresas nos garantizan una excelente calidad y disponibilidad de los productos. Recordamos que todos los [&hellip;]<\/p>\n","protected":false},"featured_media":65253,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[561,562,563,564,565],"product_tag":[],"class_list":{"0":"post-65252","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vloertegels","7":"product_cat-badkamer-tegels","8":"product_cat-keuken-tegel","9":"product_cat-wandtegels","10":"product_cat-woonkamer-tegels","12":"first","13":"outofstock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/product\/65252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/comments?post=65252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/media\/65253"}],"wp:attachment":[{"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/media?parent=65252"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/product_brand?post=65252"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/product_cat?post=65252"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tilefly.com\/nl\/wp-json\/wp\/v2\/product_tag?post=65252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}